{"id":1518,"count":2,"description":"","link":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/","name":"Solutions \u00e9nerg\u00e9tiques","slug":"solutions-energetiques","taxonomy":"product_cat","parent":1512,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/\" \/>\n<meta property=\"og:site_name\" content=\"AirMaster.ge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/\",\"url\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/\",\"name\":\"Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge\",\"isPartOf\":{\"@id\":\"https:\/\/airmaster.ge\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/airmaster.ge\/fr\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9nergies renouvelables, mesure de l'\u00e9nergie \u00e9olienne et solaire\",\"item\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LiDAR Produits de t\u00e9l\u00e9d\u00e9tection\",\"item\":\"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Solutions \u00e9nerg\u00e9tiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/airmaster.ge\/#website\",\"url\":\"https:\/\/airmaster.ge\/\",\"name\":\"Geotherm\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/airmaster.ge\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/airmaster.ge\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/airmaster.ge\/#organization\",\"name\":\"Geotherm\",\"url\":\"https:\/\/airmaster.ge\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/airmaster.ge\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/airmaster.ge\/wp-content\/uploads\/2026\/03\/airmaster-SEO.png\",\"contentUrl\":\"https:\/\/airmaster.ge\/wp-content\/uploads\/2026\/03\/airmaster-SEO.png\",\"width\":1536,\"height\":1024,\"caption\":\"Geotherm\"},\"image\":{\"@id\":\"https:\/\/airmaster.ge\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge","og_url":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/","og_site_name":"AirMaster.ge","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/","url":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/","name":"Solutions \u00e9nerg\u00e9tiques Archives - AirMaster.ge","isPartOf":{"@id":"https:\/\/airmaster.ge\/#website"},"breadcrumb":{"@id":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/solutions-energetiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/airmaster.ge\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"\u00c9nergies renouvelables, mesure de l'\u00e9nergie \u00e9olienne et solaire","item":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/"},{"@type":"ListItem","position":3,"name":"LiDAR Produits de t\u00e9l\u00e9d\u00e9tection","item":"https:\/\/airmaster.ge\/fr\/categorie-produit\/energies-renouvelables-mesure-de-lenergie-eolienne-et-solaire-fr\/lidar-sensing-teledetection-fr\/"},{"@type":"ListItem","position":4,"name":"Solutions \u00e9nerg\u00e9tiques"}]},{"@type":"WebSite","@id":"https:\/\/airmaster.ge\/#website","url":"https:\/\/airmaster.ge\/","name":"Geotherm","description":"","publisher":{"@id":"https:\/\/airmaster.ge\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/airmaster.ge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/airmaster.ge\/#organization","name":"Geotherm","url":"https:\/\/airmaster.ge\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/airmaster.ge\/#\/schema\/logo\/image\/","url":"https:\/\/airmaster.ge\/wp-content\/uploads\/2026\/03\/airmaster-SEO.png","contentUrl":"https:\/\/airmaster.ge\/wp-content\/uploads\/2026\/03\/airmaster-SEO.png","width":1536,"height":1024,"caption":"Geotherm"},"image":{"@id":"https:\/\/airmaster.ge\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/airmaster.ge\/fr\/wp-json\/wp\/v2\/product_cat\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airmaster.ge\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/airmaster.ge\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/airmaster.ge\/fr\/wp-json\/wp\/v2\/product_cat\/1512"}],"wp:post_type":[{"href":"https:\/\/airmaster.ge\/fr\/wp-json\/wp\/v2\/product?product_cat=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}